{"id":82942,"date":"2026-07-11T13:29:19","date_gmt":"2026-07-11T19:29:19","guid":{"rendered":"https:\/\/elinformanteqro.com\/noticias\/?p=82942"},"modified":"2026-07-13T13:29:55","modified_gmt":"2026-07-13T19:29:55","slug":"mas-de-mil-400-atenciones-se-han-brindado-a-traves-de-orientatel","status":"publish","type":"post","link":"https:\/\/elinformanteqro.com\/noticias\/mas-de-mil-400-atenciones-se-han-brindado-a-traves-de-orientatel\/","title":{"rendered":"M\u00e1s de mil 400 atenciones se han brindado a trav\u00e9s de Orientatel"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>La l\u00ednea telef\u00f3nica est\u00e1 disponible las 24 horas del d\u00eda.<\/li>\n\n\n\n<li>No es una l\u00ednea para atender emergencias ni denuncias an\u00f3nimas.<\/li>\n\n\n\n<li>Personal policial de Atenci\u00f3n a V\u00edctimas cuenta con certificaciones nacionales.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Seguridad P\u00fablica Municipal de Quer\u00e9taro (SSPMQ) a trav\u00e9s del personal policial adscrito a la Direcci\u00f3n de Atenci\u00f3n a V\u00edctimas de Violencia Familiar y de G\u00e9nero (DAVVFG) ha brindado mil 402 atenciones telef\u00f3nicas mediante la l\u00ednea Orientatel, en lo que va de la presente administraci\u00f3n 2024-2027.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta l\u00ednea de atenci\u00f3n telef\u00f3nica (442 100 22 22) funciona las 24 horas del d\u00eda, todos los d\u00edas del a\u00f1o, y tiene como objetivo atender llamadas de personas que tengan alguna duda con cuestiones de violencia familiar y\/o de g\u00e9nero, medidas de protecci\u00f3n, atenciones psicol\u00f3gicas o dependencias de atenci\u00f3n en esas tem\u00e1ticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los principales temas que se han recibido en la actual administraci\u00f3n, mediante la l\u00ednea telef\u00f3nica Orientatel, son aquellas relacionadas con atenciones a violencia familiar y de g\u00e9nero, psicol\u00f3gica, personas adultas mayores y relacionadas con la familia, tomando en cuenta que no es un tel\u00e9fono para recibir emergencias ni denuncias an\u00f3nimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte del compromiso de la SSPMQ por brindar un servicio profesional, especializado y de calidad, el personal policial de la DAVVFG se encuentra plenamente capacitado y certificado en tres diferentes est\u00e1ndares de competencia avalados por el Consejo Nacional de Normalizaci\u00f3n y Certificaci\u00f3n de Competencias Labores (CONOCER).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta la fecha, nueve servidores p\u00fablicos est\u00e1n certificados en el est\u00e1ndar EC1235, \u201cAtenci\u00f3n de primer contacto para la b\u00fasqueda de personas desaparecidas y no localizadas\u201d; 17 personas en el est\u00e1ndar EC1172 \u201cAcompa\u00f1amiento inicial para la atenci\u00f3n a v\u00edctimas; y 20 en el est\u00e1ndar EC0497 \u201cOrientaci\u00f3n telef\u00f3nica a mujeres y v\u00edctimas de violencia basada en el g\u00e9nero\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Seguridad P\u00fablica Municipal de Quer\u00e9taro (SSPMQ) a trav\u00e9s del personal policial adscrito a la Direcci\u00f3n de Atenci\u00f3n a V\u00edctimas de Violencia Familiar y de G\u00e9nero (DAVVFG) ha brindado mil 402 atenciones telef\u00f3nicas mediante la l\u00ednea Orientatel, en lo que va de la presente administraci\u00f3n 2024-2027. Esta l\u00ednea de atenci\u00f3n telef\u00f3nica (442 100 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":82943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-82942","post","type-post","status-publish","format-standard","has-post-thumbnail","category-queretaro"],"_links":{"self":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts\/82942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/comments?post=82942"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts\/82942\/revisions"}],"predecessor-version":[{"id":82944,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts\/82942\/revisions\/82944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/media\/82943"}],"wp:attachment":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/media?parent=82942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/categories?post=82942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/tags?post=82942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}