{"id":83006,"date":"2026-07-13T17:44:35","date_gmt":"2026-07-13T23:44:35","guid":{"rendered":"https:\/\/elinformanteqro.com\/noticias\/?p=83006"},"modified":"2026-07-13T17:44:36","modified_gmt":"2026-07-13T23:44:36","slug":"detienen-en-queretaro-a-presunto-feminicida-buscado-por-autoridades-de-tlaxcala","status":"publish","type":"post","link":"https:\/\/elinformanteqro.com\/noticias\/detienen-en-queretaro-a-presunto-feminicida-buscado-por-autoridades-de-tlaxcala\/","title":{"rendered":"Detienen en Quer\u00e9taro a presunto feminicida buscado por autoridades de Tlaxcala"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u2022 La captura fue posible mediante la estrategia Sinergia y la coordinaci\u00f3n entre corporaciones federales y estatales; el imputado era requerido por un feminicidio ocurrido en 2016.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado de la estrategia <strong>Sinergia<\/strong> y de la colaboraci\u00f3n entre autoridades federales y estatales, fue cumplimentada en Quer\u00e9taro una orden de aprehensi\u00f3n en contra de <strong>Mario \u201cN\u201d<\/strong>, quien era buscado por la Fiscal\u00eda General del Estado de Tlaxcala por su probable responsabilidad en el delito de feminicidio, cometido en 2016.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General del Estado de Quer\u00e9taro inform\u00f3 que las investigaciones realizadas por las autoridades tlaxcaltecas permitieron establecer la probable participaci\u00f3n del imputado en los hechos, por lo que se obtuvo el mandato judicial correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derivado de los mecanismos de colaboraci\u00f3n entre elementos de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana, la Polic\u00eda de Investigaci\u00f3n del Delito de Quer\u00e9taro y sus hom\u00f3logos de Tlaxcala, el presunto responsable fue localizado y detenido en territorio queretano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras su aseguramiento, Mario \u201cN\u201d fue puesto a disposici\u00f3n de la autoridad competente, que dar\u00e1 continuidad al proceso penal correspondiente en el estado de Tlaxcala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General del Estado de Quer\u00e9taro destac\u00f3 que este resultado refleja la coordinaci\u00f3n permanente con las instituciones de procuraci\u00f3n de justicia del pa\u00eds para combatir la impunidad y garantizar el acceso a la justicia para las v\u00edctimas y sus familias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 La captura fue posible mediante la estrategia Sinergia y la coordinaci\u00f3n entre corporaciones federales y estatales; el imputado era requerido por un feminicidio ocurrido en 2016. Como resultado de la estrategia Sinergia y de la colaboraci\u00f3n entre autoridades federales y estatales, fue cumplimentada en Quer\u00e9taro una orden de aprehensi\u00f3n en contra de Mario \u201cN\u201d, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":83007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-83006","post","type-post","status-publish","format-standard","has-post-thumbnail","category-queretaro"],"_links":{"self":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts\/83006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/comments?post=83006"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts\/83006\/revisions"}],"predecessor-version":[{"id":83008,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts\/83006\/revisions\/83008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/media\/83007"}],"wp:attachment":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/media?parent=83006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/categories?post=83006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/tags?post=83006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}