{"id":83051,"date":"2026-07-14T19:25:12","date_gmt":"2026-07-15T01:25:12","guid":{"rendered":"https:\/\/elinformanteqro.com\/noticias\/?p=83051"},"modified":"2026-07-14T19:25:13","modified_gmt":"2026-07-15T01:25:13","slug":"llevan-estrategia-turismoporlaninez-a-penamiller-para-prevenir-la-explotacion-infantil","status":"publish","type":"post","link":"https:\/\/elinformanteqro.com\/noticias\/llevan-estrategia-turismoporlaninez-a-penamiller-para-prevenir-la-explotacion-infantil\/","title":{"rendered":"Llevan estrategia #TurismoPorLaNi\u00f1ez a Pe\u00f1amiller para prevenir la explotaci\u00f3n infantil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u2022 La Secretar\u00eda de Turismo fortalece la capacitaci\u00f3n y el trabajo coordinado con prestadores de servicios y autoridades para promover destinos seguros para ni\u00f1as, ni\u00f1os y adolescentes.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Turismo del estado de Quer\u00e9taro (SECTUR) implement\u00f3 en el municipio de Pe\u00f1amiller la estrategia <strong>#TurismoPorLaNi\u00f1ez<\/strong>, una iniciativa orientada a prevenir la explotaci\u00f3n de ni\u00f1as, ni\u00f1os y adolescentes en el sector tur\u00edstico mediante acciones de capacitaci\u00f3n, sensibilizaci\u00f3n y coordinaci\u00f3n entre autoridades, sociedad civil y prestadores de servicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la presentaci\u00f3n de la estrategia, la secretaria de Turismo, Adriana Vega V\u00e1zquez Mellado, se\u00f1al\u00f3 que el turismo solo puede consolidarse como un verdadero motor de desarrollo cuando pone en el centro a las personas, especialmente a la infancia, por lo que destac\u00f3 la importancia de fortalecer entornos seguros para este sector de la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La funcionaria explic\u00f3 que la estrategia fue desarrollada con el respaldo del Sistema Integral de Protecci\u00f3n de Ni\u00f1as, Ni\u00f1os y Adolescentes (SIPINNA), la Procuradur\u00eda Especializada, la Secretar\u00eda de Gobierno y otras instituciones, como parte de una pol\u00edtica impulsada por el Gobierno del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHoy este esfuerzo llega a la Sierra Gorda y al Semidesierto, donde el turismo tiene un profundo v\u00ednculo con las comunidades, con la naturaleza y con la identidad local. Implementar aqu\u00ed esta estrategia significa fortalecer un modelo de turismo m\u00e1s consciente, m\u00e1s humano y m\u00e1s cercano a la gente\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adriana Vega record\u00f3 que, por instrucci\u00f3n del gobernador Mauricio Kuri Gonz\u00e1lez, la Secretar\u00eda de Turismo promueve de manera permanente el <strong>C\u00f3digo Nacional de Conducta para la Protecci\u00f3n de Ni\u00f1as, Ni\u00f1os y Adolescentes en el Sector de los Viajes y el Turismo<\/strong>, adem\u00e1s de ofrecer procesos de capacitaci\u00f3n dirigidos a prestadores de servicios tur\u00edsticos para prevenir cualquier forma de violencia o explotaci\u00f3n infantil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, reconoci\u00f3 la colaboraci\u00f3n del SIPINNA, World Vision M\u00e9xico, la Secretar\u00eda de Gobierno y el municipio de Pe\u00f1amiller, instituciones que han unido esfuerzos para extender esta estrategia a la Sierra Gorda y fortalecer una cultura de corresponsabilidad en favor de la ni\u00f1ez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de la implementaci\u00f3n de <strong>#TurismoPorLaNi\u00f1ez<\/strong>, participaron representantes de caba\u00f1as, campamentos, restaurantes, fondas, gu\u00edas tur\u00edsticos y operadores de transporte p\u00fablico en la modalidad de taxi, quienes recibieron informaci\u00f3n y herramientas para identificar, prevenir y denunciar situaciones que vulneren los derechos de ni\u00f1as, ni\u00f1os y adolescentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas acciones, el Gobierno del Estado busca consolidar destinos tur\u00edsticos seguros, responsables y comprometidos con la protecci\u00f3n de la infancia, promoviendo la participaci\u00f3n activa de autoridades, empresas y sociedad civil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 La Secretar\u00eda de Turismo fortalece la capacitaci\u00f3n y el trabajo coordinado con prestadores de servicios y autoridades para promover destinos seguros para ni\u00f1as, ni\u00f1os y adolescentes. La Secretar\u00eda de Turismo del estado de Quer\u00e9taro (SECTUR) implement\u00f3 en el municipio de Pe\u00f1amiller la estrategia #TurismoPorLaNi\u00f1ez, una iniciativa orientada a prevenir la explotaci\u00f3n de ni\u00f1as, ni\u00f1os [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":83052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-83051","post","type-post","status-publish","format-standard","has-post-thumbnail","category-queretaro"],"_links":{"self":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts\/83051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/comments?post=83051"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts\/83051\/revisions"}],"predecessor-version":[{"id":83053,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/posts\/83051\/revisions\/83053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/media\/83052"}],"wp:attachment":[{"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/media?parent=83051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/categories?post=83051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteqro.com\/noticias\/wp-json\/wp\/v2\/tags?post=83051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}